{"id":39653,"date":"2022-03-11T10:59:52","date_gmt":"2022-03-11T09:59:54","guid":{"rendered":"https:\/\/niarosa.si\/?post_type=product&#038;p=39653"},"modified":"2022-03-14T09:54:10","modified_gmt":"2022-03-14T08:54:10","slug":"completo-sportivo-da-donna-in-due-pezzi-gina-nero","status":"publish","type":"product","link":"https:\/\/niarosa.si\/it\/prodotto\/completo-sportivo-da-donna-in-due-pezzi-gina-nero\/","title":{"rendered":"Completo sportivo da donna in due pezzi Gina, nero"},"content":{"rendered":"<p>Materiale: 72% cotone, 22% poliestere, 6% elastan<br \/>\nLavaggio: lavare in lavatrice a 30\u00b0C<br \/>\nColore: come mostrato<br \/>\nStile\/modello: classico<br \/>\nTaglie: taglia unica (S\/M)<\/p>\n<p>Il modello nella foto indossa una S (altezza 175 cm, busto 85 cm, vita 65 cm, fianchi 89 cm).<\/p>\n<p>&nbsp;<\/p>\n<p><strong>GUIDA TAGLIE (misura in cm):<\/strong><\/p>\n<table width=\"793\">\n<tbody>\n<tr>\n<td width=\"70\">TAGLIA<\/td>\n<td width=\"142\">NO. DI CONFEZIONE<\/td>\n<td width=\"153\">PETTO CIRCONFERENZA<\/td>\n<td width=\"157\">VITA CIRCONFERENZA<\/td>\n<td width=\"179\">FIANCHI CIRCONFERENZA<\/td>\n<td width=\"92\">ALTEZZA<\/td>\n<\/tr>\n<tr>\n<td>XS<\/td>\n<td>34<\/td>\n<td>78<\/td>\n<td>63-70<\/td>\n<td>87<\/td>\n<td>156-164<\/td>\n<\/tr>\n<tr>\n<td>S<\/td>\n<td>36<\/td>\n<td>82<\/td>\n<td>72-80<\/td>\n<td>90<\/td>\n<td>160-168<\/td>\n<\/tr>\n<tr>\n<td>M<\/td>\n<td>38<\/td>\n<td>86<\/td>\n<td>78-86<\/td>\n<td>94<\/td>\n<td>162-172<\/td>\n<\/tr>\n<tr>\n<td>L<\/td>\n<td>40<\/td>\n<td>91<\/td>\n<td>84-90<\/td>\n<td>102<\/td>\n<td>164-174<\/td>\n<\/tr>\n<tr>\n<td>XL<\/td>\n<td>42<\/td>\n<td>96<\/td>\n<td>88-96<\/td>\n<td>106<\/td>\n<td>166-178<\/td>\n<\/tr>\n<tr>\n<td>XXL<\/td>\n<td>44<\/td>\n<td>100<\/td>\n<td>84-91<\/td>\n<td>110<\/td>\n<td>168-180<\/td>\n<\/tr>\n<\/tbody>\n<\/table>\n","protected":false},"excerpt":{"rendered":"<p>La tuta Gina con giacca corta \u00e8 realizzata in tessuto pi\u00f9 spesso, ottimo per le giornate pi\u00f9 fredde. Il taglio ampio del set ti consente comfort e libert\u00e0 di movimento.<\/p>\n","protected":false},"featured_media":40119,"comment_status":"closed","ping_status":"closed","template":"","meta":[],"product_brand":[],"product_cat":[583,451],"product_tag":[],"class_list":["post-39653","product","type-product","status-publish","has-post-thumbnail","product_cat-abbigliamento","product_cat-sets-it","pa_barva-nero","first","instock","sale","featured","taxable","shipping-taxable","purchasable","product-type-variable","rtwpvs-product"],"_links":{"self":[{"href":"https:\/\/niarosa.si\/it\/wp-json\/wp\/v2\/product\/39653","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/niarosa.si\/it\/wp-json\/wp\/v2\/product"}],"about":[{"href":"https:\/\/niarosa.si\/it\/wp-json\/wp\/v2\/types\/product"}],"replies":[{"embeddable":true,"href":"https:\/\/niarosa.si\/it\/wp-json\/wp\/v2\/comments?post=39653"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/niarosa.si\/it\/wp-json\/wp\/v2\/media\/40119"}],"wp:attachment":[{"href":"https:\/\/niarosa.si\/it\/wp-json\/wp\/v2\/media?parent=39653"}],"wp:term":[{"taxonomy":"product_brand","embeddable":true,"href":"https:\/\/niarosa.si\/it\/wp-json\/wp\/v2\/product_brand?post=39653"},{"taxonomy":"product_cat","embeddable":true,"href":"https:\/\/niarosa.si\/it\/wp-json\/wp\/v2\/product_cat?post=39653"},{"taxonomy":"product_tag","embeddable":true,"href":"https:\/\/niarosa.si\/it\/wp-json\/wp\/v2\/product_tag?post=39653"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}